{"id":23883,"date":"2025-08-14T15:00:16","date_gmt":"2025-08-14T13:00:16","guid":{"rendered":"https:\/\/mr-congress.com\/de\/2024\/10\/17\/kamingespraeche-2\/"},"modified":"2026-03-18T09:51:15","modified_gmt":"2026-03-18T08:51:15","slug":"sdg-1-keine-armut","status":"publish","type":"post","link":"https:\/\/mr-congress.com\/de\/2025\/08\/14\/sdg-1-keine-armut\/","title":{"rendered":"SDG 1 &#8211; Keine Armut"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]<\/p>\n<h1 style=\"color: #6b6b6b;\">Gleiche Chancen im Eventmanagement.<\/h1>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image image=&#8221;23886&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][vc_column_text]<\/p>\n<blockquote>\n<h2 class=\"get-to-know.two-know\" style=\"text-align: center;\">\u2026denn Events sind Plattformen f\u00fcr Wandel.<\/h2>\n<\/blockquote>\n<p>[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1762433859384{margin-top: 3vmax !important;margin-bottom: 1vmax !important;}&#8221;]Das Thema Armut beginnt nicht nur bei den gro\u00dfen Entscheidungen in der Politik \u2013 sie zeigt sich auch in struktureller Benachteiligung, ungleichen Chancen und dem fehlenden Zugang zu wirtschaftlicher Teilhabe. Das erste Ziel der 17 Nachhaltigkeitsziele bis 2030 der Vereinten Nationen \u2013 <strong>&#8220;Keine Armut&#8221;<\/strong> \u2013 ruft dazu auf, Armut in allen Formen zu beenden. Die Vision dahinter ist es eine Welt zu schaffen, in der alle Menschen, unabh\u00e4ngig von Geschlecht, Herkunft oder sozialem Status, die <a href=\"https:\/\/mr-congress.com\/de\/unser-selbstverstandnis\/\">gleichen Chancen<\/a> erhalten. Besonders in der Eventmanagement-Branche, in der Begegnungen und Erlebnisse geschaffen werden, tragen wir Verantwortung.[\/vc_column_text][\/vc_column][\/vc_row][vc_row equal_height=&#8221;yes&#8221; css=&#8221;.vc_custom_1591794311845{margin-top: 3vmax !important;margin-bottom: 3vmax !important;}&#8221;][vc_column width=&#8221;1\/2&#8243; el_class=&#8221;v-center&#8221; css=&#8221;.vc_custom_1710160986877{padding-top: 0px !important;padding-right: 0px !important;padding-bottom: 0px !important;padding-left: 0px !important;}&#8221;][vc_single_image image=&#8221;23799&#8243; img_size=&#8221;large&#8221; css=&#8221;.vc_custom_1755171937627{background-position: center !important;background-repeat: no-repeat !important;background-size: contain !important;}&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243; el_class=&#8221;v-center&#8221;][vc_column_text el_class=&#8221;w-mid&#8221;]Armut wird nicht nur bei politischen Entscheidungen thematisiert, sondern zeigt sich auch im Alltag wenn es um die Sichtbarkeit benachteiligter Menschen und Zugang zu Bildung und gesellschaftlicher Teilhabe geht. Events k\u00f6nnen daher viel mehr sein als nur sch\u00f6ne Erinnerungen, sie schaffen R\u00e4ume in denen alle Menschen, unabh\u00e4ngig von sozialen oder wirtschaftlichen Voraussetzungen, willkommen sind und sich gesehen f\u00fchlen. Das f\u00e4ngt bei der Einplanung von niedrigschwelligen Zugangsm\u00f6glichkeiten ab und die Einbindung von Programmpunkten, die f\u00fcr verschiedene Zielgruppen relevant sind &#8211; nat\u00fcrlich immer abgestimmt mit den <a href=\"https:\/\/mr-congress.com\/de\/2018\/12\/01\/der-event-canvas\/\">Kundenw\u00fcnschen<\/a>.[\/vc_column_text][\/vc_column][\/vc_row][vc_row equal_height=&#8221;yes&#8221; css=&#8221;.vc_custom_1591794311845{margin-top: 3vmax !important;margin-bottom: 3vmax !important;}&#8221;][vc_column width=&#8221;1\/2&#8243; el_class=&#8221;v-center&#8221;][vc_column_text]Ein Schritt zur Bek\u00e4mpfung von Armut ist die St\u00e4rkung lokaler M\u00e4rkte. In der Zusammenarbeit mit lokalen Partnern \u2013 ob Catering, Technik oder Ausstattung \u2013 kann man bewusst auf regionale Betriebe und Anbieter setzen. So f\u00f6rdert man die wirtschaftliche Teilhabe vor Ort und unterst\u00fctzt nachhaltiges Wachstum in der Umgebung des Eventstandorts.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243; el_class=&#8221;v-center&#8221;][vc_single_image image=&#8221;23888&#8243; img_size=&#8221;large&#8221; alignment=&#8221;center&#8221;][\/vc_column][\/vc_row][vc_row equal_height=&#8221;yes&#8221; css=&#8221;.vc_custom_1591794311845{margin-top: 3vmax !important;margin-bottom: 3vmax !important;}&#8221;][vc_column width=&#8221;1\/2&#8243; el_class=&#8221;v-center&#8221;][vc_single_image image=&#8221;23803&#8243; img_size=&#8221;large&#8221; alignment=&#8221;center&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243; el_class=&#8221;v-center&#8221;][vc_column_text el_class=&#8221;w-mid&#8221;]Faire Arbeitsbedingungen entlang der gesamten Wertsch\u00f6pfungskette sowie die Einhaltung grundlegender Mindeststandards f\u00fcr sichere Arbeitsbedingungen und transparenter Vertr\u00e4ge sind hierbei selbstverst\u00e4ndlich. Ein nachhaltiges Wirtschaftswachstum bedeutet somit in unserer Branche: nicht nur f\u00fcr Gro\u00dfkonzerne zu arbeiten, sondern auch Projekte f\u00fcr NGOs, Bildungstr\u00e4ger oder gemeinn\u00fctzige Initiativen zu realisieren und dabei wirtschaftlich tragf\u00e4hige Modelle zu schaffen, von denen alle Seiten profitieren.[\/vc_column_text][\/vc_column][\/vc_row][vc_row equal_height=&#8221;yes&#8221; css=&#8221;.vc_custom_1591794311845{margin-top: 3vmax !important;margin-bottom: 3vmax !important;}&#8221;][vc_column width=&#8221;1\/2&#8243; el_class=&#8221;v-center&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243; el_class=&#8221;v-center&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1594823997921{margin-top: 3vmax !important;margin-bottom: 3vmax !important;}&#8221;][vc_column width=&#8221;1\/12&#8243;][\/vc_column][vc_column width=&#8221;10\/12&#8243;][vc_column_text el_class=&#8221;yellow-bar blue-square&#8221;]Laut den Vereinten Nationen lebt immer noch rund jede zehnte Person weltweit in extremer Armut \u2013 darunter 380 Millionen Frauen (Stand 2022). Nur ein Drittel aller L\u00e4nder ist aktuell auf dem Weg, das Ziel der Armutsreduktion bis 2030 zu erreichen. Aber wir glauben fest daran, dass jede Entscheidung z\u00e4hlt und wir gerade in der Veranstaltungsbranche viel tun k\u00f6nnen. Vom <a href=\"https:\/\/mr-congress.com\/de\/creacon\/\">Teamaufbau <\/a>bis zur Auswahl der Location \u2013 k\u00f6nnen wir Barrieren abbauen und gleiche Chancen f\u00f6rdern.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/12&#8243;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;2\/3&#8243;]<div class=\"ubtn-ctn-center\"><a class=\"ubtn-link ubtn-center ubtn-normal touch-btn ubtn-text ubtn ubtn-ctn-center\" href = \"mailto:c.palma@mr-congress.com?subject=Blogpost SDG 1\" target=' _blank' ><button type=\"button\" class=\"ubtn ubtn-normal ubtn-no-hover-bg  none  ubtn-center   tooltip-6a047fbebb9dd\"  data-hover=\"#c95038\" data-border-color=\"#4c4b4b\" data-bg=\"#ffffff\" data-hover-bg=\"rgba(197,230,249,0.29)\" data-border-hover=\"rgba(197,230,249,0.29)\" data-shadow-hover=\"\" data-shadow-click=\"none\" data-shadow=\"\" data-shd-shadow=\"\" style=\"font-weight:normal;border-radius:0px;border-width:4px;border-color:#4c4b4b;border-style:solid;background: #ffffff;color: #b58038;\"><span class=\"ubtn-hover\"><\/span><span class=\"ubtn-data ubtn-text\">Schreiben Sie uns<\/span><\/button><\/a><\/div>[\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/vc_row]<\/p>\n<img src=\"https:\/\/mr-congress.com\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/wallet-3548021_1280.jpg\" class=\"ss-hidden-pin-image\" alt=\"Zwei H\u00e4nde halten eine offene braune Lederb\u00f6rse mit leeren F\u00e4chern \u2013 sie symbolisieren finanzielle Schwierigkeiten und die Realit\u00e4t der Armut.\" data-pin-url=\"https:\/\/mr-congress.com\/de\/2025\/08\/14\/sdg-1-keine-armut\/\" data-pin-media=\"https:\/\/mr-congress.com\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/wallet-3548021_1280.jpg\" data-pin-description=\"SDG 1 &#8211; Keine Armut\"\/>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]<\/p>\n<p>Gleiche Chancen im Eventmanagement.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image image=&#8221;23886&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][vc_column_text]<\/p>\n<p>\u2026denn Events sind Plattformen f\u00fcr Wandel.<\/p>\n<p>[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1762433859384{margin-top: 3vmax !important;margin-bottom: 1vmax !important;}&#8221;]Das Thema Armut beginnt nicht nur bei den gro\u00dfen Entscheidungen in der Politik \u2013 sie zeigt sich auch in struktureller Benachteiligung, ungleichen Chancen und dem fehlenden Zugang zu wirtschaftlicher Teilhabe. Das erste Ziel der 17 Nachhaltigkeitsziele bis 2030 der Vereinten Nationen \u2013 &#8220;Keine Armut&#8221; \u2013 ruft dazu auf, Armut in allen Formen zu beenden. Die Vision dahinter ist es eine Welt zu schaffen, in [&#8230;]<\/p>\n<img src=\"https:\/\/mr-congress.com\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/wallet-3548021_1280.jpg\" class=\"ss-hidden-pin-image\" alt=\"Zwei H\u00e4nde halten eine offene braune Lederb\u00f6rse mit leeren F\u00e4chern \u2013 sie symbolisieren finanzielle Schwierigkeiten und die Realit\u00e4t der Armut.\" data-pin-url=\"https:\/\/mr-congress.com\/de\/2025\/08\/14\/sdg-1-keine-armut\/\" data-pin-media=\"https:\/\/mr-congress.com\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/wallet-3548021_1280.jpg\" data-pin-description=\"SDG 1 &#8211; Keine Armut\"\/>","protected":false},"author":5,"featured_media":23891,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[805],"tags":[],"_links":{"self":[{"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/posts\/23883"}],"collection":[{"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/comments?post=23883"}],"version-history":[{"count":10,"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/posts\/23883\/revisions"}],"predecessor-version":[{"id":24728,"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/posts\/23883\/revisions\/24728"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/media\/23891"}],"wp:attachment":[{"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/media?parent=23883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/categories?post=23883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/tags?post=23883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}