{"id":23973,"date":"2025-09-18T10:55:16","date_gmt":"2025-09-18T08:55:16","guid":{"rendered":"https:\/\/mr-congress.com\/de\/?p=23973"},"modified":"2026-03-18T14:23:22","modified_gmt":"2026-03-18T13:23:22","slug":"sdg-5-geschlechtergleichheit","status":"publish","type":"post","link":"https:\/\/mr-congress.com\/de\/2025\/09\/18\/sdg-5-geschlechtergleichheit\/","title":{"rendered":"SDG 5 &#8211; Geschlechtergleichheit"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]<\/p>\n<h1 style=\"color: #6b6b6b;\">Gleichberechtigung beginnt bei den Details.<\/h1>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image image=&#8221;23976&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][vc_column_text]<\/p>\n<blockquote>\n<h2>\u2026 Events k\u00f6nnen ausreichend Raum f\u00fcr alle schaffen<\/h2>\n<\/blockquote>\n<p>[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1762441664445{margin-top: 3vmax !important;margin-bottom: 1vmax !important;}&#8221;]Gleichberechtigung ist kein Sonderthema, sie ist zentraler Bestandteil einer gerechten Gesellschaft. Das f\u00fcnfte Ziel der Vereinten Nationen besch\u00e4ftigt sich vor Allem mit der gleichberechtigten Beteiligung von Frauen am sozialen, politischen und wirtschaftlichen Leben. Doch was bedeutet das genau f\u00fcr die Eventbranche?<\/p>\n<p>Tats\u00e4chlich l\u00e4sst sich Gleichstellung an vielen Stellen einbringen. <a href=\"https:\/\/mr-congress.com\/de\/meetings-und-tagungen\/\">Veranstaltungen<\/a> bieten eine gute M\u00f6glichkeit, Gleichberechtigung nicht nur zu f\u00f6rdern, sondern auch ganz praktisch umzusetzen und sichtbar zu machen.[\/vc_column_text][\/vc_column][\/vc_row][vc_row equal_height=&#8221;yes&#8221; css=&#8221;.vc_custom_1591794311845{margin-top: 3vmax !important;margin-bottom: 3vmax !important;}&#8221;][vc_column][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;23978&#8243; img_size=&#8221;large&#8221; alignment=&#8221;center&#8221; css=&#8221;.vc_custom_1762442326401{background-position: center !important;background-repeat: no-repeat !important;background-size: contain !important;}&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;33px&#8221;][vc_column_text el_class=&#8221;w-mid&#8221;]<\/p>\n<p style=\"text-align: left;\">Ein Ansatz ist, schon bei der Zusammenstellung von <a href=\"https:\/\/mr-congress.com\/en\/team\/\">Teams<\/a> auf eine ausgewogene Geschlechterverteilung zu achten. W\u00e4hrend Frauen in technischen Bereichen der Veranstaltungswirtschaft weiterhin stark unterrepr\u00e4sentiert sind, ist das Berufsfeld Eventmanagement selbst oft frauendominiert. Auch das zeigt: Geschlechtergleichstellung bedeutet nicht nur, Frauen zu st\u00e4rken, sondern auch M\u00e4nner dort sichtbar zu machen, wo sie seltener vertreten sind. Es geht um ein echtes Gleichgewicht und eine Vielfalt auf allen Ebenen \u2013 unabh\u00e4ngig vom Geschlecht.<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_empty_space][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;40px&#8221;][vc_column_text]Zudem k\u00f6nnen mitarbeiterorientierte Strukturen wie zum Beispiel flexible Einsatzzeiten f\u00fcr Menschen mit Care-Verantwortung oder f\u00fcr werdende M\u00fctter helfen, diverse Lebensrealit\u00e4ten besser einzubinden und umsetzen zu k\u00f6nnen. Aber auch bei Stellenausschreibungen oder Projektbesetzungen muss ber\u00fccksichtigt werden, dass klare Kriterien zur Gleichstellung formuliert werden \u2013 als Teil einer inklusiveren <a href=\"https:\/\/mr-congress.com\/de\/vision-mission\/\">Unternehmensstrategie<\/a>.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;23979&#8243; img_size=&#8221;large&#8221; alignment=&#8221;right&#8221;][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=&#8221;40px&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;23980&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;20px&#8221;][vc_column_text el_class=&#8221;w-mid&#8221;]Schlie\u00dflich ist auch die Sprachform, mit der kommuniziert wird, in Einladungen, auf B\u00fchnen oder in den Programmheften, ein wichtiger sozialer Faktor. Schon die bewusste Entscheidung f\u00fcr eine geschlechtersensible Formulierung wird als erstes Merkmal f\u00fcr gelebte Inklusion wahrgenommen. Aber auch an die Zugangsgerechtigkeit bei Sanit\u00e4reinrichtungen sollte gedacht werden: durch barrierefreie Toiletten, sichere Hygienebereiche f\u00fcr alle Geschlechter sowie zum Beispiel, wenn m\u00f6glich, die kostenlose Bereitstellung von Menstruationsprodukten, worauf die Eventteilnehmer*innen sicherlich ein wertsch\u00e4tzendes Auge legen werden.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_empty_space][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1594823997921{margin-top: 3vmax !important;margin-bottom: 3vmax !important;}&#8221;][vc_column width=&#8221;1\/12&#8243;][\/vc_column][vc_column width=&#8221;10\/12&#8243;][vc_column_text el_class=&#8221;yellow-bar blue-square&#8221;]Vielleicht gelingt es so, aus jedem Event ein kleines, bedeutsames Statement zu machen \u2013 f\u00fcr Sichtbarkeit, echte Chancengleichheit und gegenseitigen Respekt. Und das w\u00e4re ein wirklich starker Anfang.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/12&#8243;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;2\/3&#8243;]<div class=\"ubtn-ctn-center\"><a class=\"ubtn-link ubtn-center ubtn-normal touch-btn ubtn-text ubtn ubtn-ctn-center\" href = \"mailto:c.palma@mr-congress.com?subject=Blogpost SDG 5\" target=' _blank' ><button type=\"button\" class=\"ubtn ubtn-normal ubtn-no-hover-bg  none  ubtn-center   tooltip-6a56fe273b109\"  data-hover=\"#c95038\" data-border-color=\"#4c4b4b\" data-bg=\"#ffffff\" data-hover-bg=\"rgba(197,230,249,0.29)\" data-border-hover=\"rgba(197,230,249,0.29)\" data-shadow-hover=\"\" data-shadow-click=\"none\" data-shadow=\"\" data-shd-shadow=\"\" style=\"font-weight:normal;border-radius:0px;border-width:4px;border-color:#4c4b4b;border-style:solid;background: #ffffff;color: #b58038;\"><span class=\"ubtn-hover\"><\/span><span class=\"ubtn-data ubtn-text\">Schreiben Sie uns<\/span><\/button><\/a><\/div>[\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/vc_row]<\/p>\n<img src=\"https:\/\/mr-congress.com\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/pride-parade-2635591_1280.jpg\" class=\"ss-hidden-pin-image\" alt=\"A person in a bright, feathered costume is kissed on the cheek by another person. Represents diversity, acceptance, and freedom of identity and expression regardless of gender or role.\" data-pin-url=\"https:\/\/mr-congress.com\/de\/2025\/09\/18\/sdg-5-geschlechtergleichheit\/\" data-pin-media=\"https:\/\/mr-congress.com\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/pride-parade-2635591_1280.jpg\" data-pin-description=\"SDG 5 &#8211; Geschlechtergleichheit\"\/>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]<\/p>\n<p>Gleichberechtigung beginnt bei den Details.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image image=&#8221;23976&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][vc_column_text]<\/p>\n<p>\u2026 Events k\u00f6nnen ausreichend Raum f\u00fcr alle schaffen<\/p>\n<p>[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1762441664445{margin-top: 3vmax !important;margin-bottom: 1vmax !important;}&#8221;]Gleichberechtigung ist kein Sonderthema, sie ist zentraler Bestandteil einer gerechten Gesellschaft. Das f\u00fcnfte Ziel der Vereinten Nationen besch\u00e4ftigt sich vor Allem mit der gleichberechtigten Beteiligung von Frauen am sozialen, politischen und wirtschaftlichen Leben. Doch was bedeutet das genau f\u00fcr die Eventbranche?<\/p>\n<p>Tats\u00e4chlich l\u00e4sst sich Gleichstellung an vielen Stellen einbringen. Veranstaltungen bieten eine gute M\u00f6glichkeit, Gleichberechtigung nicht nur zu f\u00f6rdern, sondern auch ganz [&#8230;]<\/p>\n<img src=\"https:\/\/mr-congress.com\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/pride-parade-2635591_1280.jpg\" class=\"ss-hidden-pin-image\" alt=\"A person in a bright, feathered costume is kissed on the cheek by another person. Represents diversity, acceptance, and freedom of identity and expression regardless of gender or role.\" data-pin-url=\"https:\/\/mr-congress.com\/de\/2025\/09\/18\/sdg-5-geschlechtergleichheit\/\" data-pin-media=\"https:\/\/mr-congress.com\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/pride-parade-2635591_1280.jpg\" data-pin-description=\"SDG 5 &#8211; Geschlechtergleichheit\"\/>","protected":false},"author":5,"featured_media":23977,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[805],"tags":[],"_links":{"self":[{"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/posts\/23973"}],"collection":[{"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/comments?post=23973"}],"version-history":[{"count":10,"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/posts\/23973\/revisions"}],"predecessor-version":[{"id":24800,"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/posts\/23973\/revisions\/24800"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/media\/23977"}],"wp:attachment":[{"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/media?parent=23973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/categories?post=23973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/tags?post=23973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}