{"id":7477,"date":"2017-09-08T08:00:15","date_gmt":"2017-09-08T06:00:15","guid":{"rendered":"https:\/\/mr-congress.com\/de\/2017\/08\/11\/copy-of-wohnungsmuseum-prenzlauer-berg\/"},"modified":"2026-04-30T15:56:46","modified_gmt":"2026-04-30T13:56:46","slug":"hurricane_factory_berlin","status":"publish","type":"post","link":"https:\/\/mr-congress.com\/de\/2017\/09\/08\/hurricane_factory_berlin\/","title":{"rendered":"Hurricane Factory Berlin"},"content":{"rendered":"<p>[vc_row][vc_column][vc_single_image image=&#8221;7485&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][vc_column_text]<\/p>\n<blockquote>\n<h2>&#8220;Der Traum vom Fliegen in der Hurricane Factory Berlin&#8221;<\/h2>\n<\/blockquote>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1493169522556{margin-top: 30px !important;margin-bottom: 30px !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;50px&#8221;][vc_single_image image=&#8221;7487&#8243; img_size=&#8221;full&#8221; add_caption=&#8221;yes&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text el_class=&#8221;m-blog-text-right&#8221;]<\/p>\n<h3 style=\"color: #54c6c3;\">Die Hurricane Factory erf\u00fcllt den Traum vom Fliegen<\/h3>\n<p>Fliegen ist seit jeher ein Menschheitstraum. Da wir aber leider anatomisch nicht f\u00fcr die bodenferne Fortbewegung geeignet sind, suchen wir immer wieder nach neuen M\u00f6glichkeiten, uns so schwerelos wie m\u00f6glich zu f\u00fchlen. Schwerelosigkeit gibt es seit Neuestem auch in Sch\u00f6nefeld: Hier hat vor kurzem erst der bislang gr\u00f6\u00dfte Windkanal Deutschlands er\u00f6ffnet.<br \/>\nNoch bevor man am zuk\u00fcnftigen Hauptstadiflughafen BER abheben kann, kann sich jeder in der neuen Hurricane Factory den Traum vom Fliegen erf\u00fcllen.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_column_text css=&#8221;.vc_custom_1771434951786{background-color: #ffffff !important;}&#8221; el_class=&#8221;.m-blog-text-left&#8221;]<\/p>\n<h3 style=\"color: #54c6c3;\">Freies Fliegen auf 280 hm\/h schnellem Wind<\/h3>\n<p>Ich war zur Er\u00f6ffnungsfeier eingeladen und durfte einmal Probefliegen. Das erste, was einem auff\u00e4llt, wenn man den Hauptraum der Hurricane Factory betritt, ist der riesige verglaste Flugzylinder in der Mitte des Raumes. Ein bis zu 280 Stundenkilometer schneller Wind erm\u00f6glicht freies Fliegen auf 15 Metern.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;7486&#8243; img_size=&#8221;full&#8221; add_caption=&#8221;yes&#8221;][vc_empty_space height=&#8221;50px&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1493626002276{margin-bottom: 30px !important;}&#8221;][vc_column width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;7481&#8243; img_size=&#8221;full&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;7484&#8243; img_size=&#8221;full&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;7483&#8243; img_size=&#8221;full&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1493169522556{margin-top: 30px !important;margin-bottom: 30px !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;50px&#8221;][vc_column_text]Gemeinsam mit den anderen G\u00e4sten checkte ich an der Rezeption ein und wurde nach einem mir durch die Aufregung sehr willkommenen Willkommensdrink gemeinsam mit den anderen Fliegern eingewiesen. Uns wurde der Ablauf erkl\u00e4rt, wie wir unseren K\u00f6rper im Wind am besten positionieren und andere n\u00fctzliche Tipps gegeben. Nach dieser kleinen Einweisung wurden wir mit einem Overall, Helm und einer Brille ausgestattet, die die Augen vor dem Wind im Windkanal sch\u00fctzen soll. Nachdem ich all diese Utensilien angelegt hatte, f\u00fchlte ich mich schon etwas vorbereiteter und professioneller.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;50px&#8221;][vc_column_text]Mit der ganzen Gruppe ging es dann in den Unterdruckraum, den Vorraum zum Flugzylinder. Hier angekommen verstand ich, warum man usn zus\u00e4tzlich zur Pflichtausstattung noch Ohrenst\u00f6psel ans Herz gelegt hat; So ein Windkanal erzeugt eine beachtliche Ger\u00e4uschkulisse.<br \/>\nNat\u00fcrlich wurde ich als allererste vom Flugtrainer in den Kanal hineingewunken. Nach Anweisung und gegen jeden Instinkt lie\u00df ich mich einfach der L\u00e4nge nach in den Windkanal fallen und anstatt wie bef\u00fcrchtet auf dem Boden aufzuprallen, schwebe ich tats\u00e4chlich mitten in der Luft. [\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1493169522556{margin-top: 30px !important;margin-bottom: 30px !important;}&#8221;][vc_column][vc_separator color=&#8221;custom&#8221; el_width=&#8221;10&#8243; accent_color=&#8221;#54c6c3&#8243; el_class=&#8221;m-blog-devider&#8221;][vc_column_text css=&#8221;.vc_custom_1771434909212{padding-bottom: 30px !important;}&#8221;]<\/p>\n<h3 style=\"text-align: center; color: #54c6c3;\">Das ultimative Gef\u00fchl von Schwerelosigkeit<\/h3>\n<p>[\/vc_column_text][vc_column_text]Ein unglaubliches Gef\u00fchl, v\u00f6llig ohne Hilfsmittel auf dem Wind zu gleiten. Der Fluginstruktor war die ganze Zeit da und half mir, mich auf dem Aufwind durch den Kanal zu bewegen. H\u00f6hepunkt war der Auf- und Abstieg auf die vollen 15 Meter H\u00f6he des Zylinders, der das ultimative Gef\u00fchl von Schwerelosigkeit vermittelt.[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1493628240400{margin-bottom: 60px !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;7488&#8243; img_size=&#8221;600&#215;300&#8243; add_caption=&#8221;yes&#8221; alignment=&#8221;right&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text el_class=&#8221;m-blog-text-background-right&#8221; css=&#8221;.vc_custom_1503570218807{margin-top: 60px !important;}&#8221;]<\/p>\n<ul>\n<li>Die Berliner Hurricane Factory ist kein neues Modell \u2013<\/li>\n<li>sie betreibt bislang schon \u00e4hnliche Anlagen<\/li>\n<li>in Prag, in Madrid und im slowakischen Tatralandia.<\/li>\n<li>Weitere Windkan\u00e4le in ganz Europa sind in Planung.<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1493628240400{margin-bottom: 60px !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_column_text el_class=&#8221;m-blog-text-left&#8221; css=&#8221;.vc_custom_1503570238846{margin-top: 60px !important;}&#8221;]Der Windkanal der Hurricane Factory ist sowohl f\u00fcr kleinere Gruppen als auch f\u00fcr Gro\u00dfevents mit bis zu 270 Personen geeignet. Das Hauptgeschoss, in dem sich der Windkanak und Zuschauerbereich befindet, fasst ca. 150 Personen. Der separate Veranstaltungsraum bietet zus\u00e4tzlich Platz f\u00fcr ca. 120 Personen. Die Anlage ist auch exklusiv zu mieten.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;7489&#8243; img_size=&#8221;600&#215;300&#8243; add_caption=&#8221;yes&#8221;][\/vc_column][\/vc_row]<\/p>\n<img src=\"https:\/\/mr-congress.com\/de\/wp-content\/uploads\/sites\/3\/2017\/08\/Hurricane_Factory_Windkanal_Flieger.jpg\" class=\"ss-hidden-pin-image\" alt=\"hurricane factory berlin, hurricane factory, hurricane factory prague, hurricane factory madrid, fliegen, windkanal, windkanal berlin, hurricane, flugsimulator, sch\u00f6nefeld, BER, berlin sch\u00f6nefeld, fliegen, location berlin, sightseeing berlin, must see berlin, adventure berlin, abenteuer berlin, action, action berlin, flight simulator berlin, adrenalin berlin,\" data-pin-url=\"https:\/\/mr-congress.com\/de\/2017\/09\/08\/hurricane_factory_berlin\/\" data-pin-media=\"https:\/\/mr-congress.com\/de\/wp-content\/uploads\/sites\/3\/2017\/08\/Hurricane_Factory_Windkanal_Flieger.jpg\" data-pin-description=\"Hurricane Factory Berlin\"\/>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_single_image image=&#8221;7485&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][vc_column_text]<\/p>\n<p>&#8220;Der Traum vom Fliegen in der Hurricane Factory Berlin&#8221;<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1493169522556{margin-top: 30px !important;margin-bottom: 30px !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_empty_space height=&#8221;50px&#8221;][vc_single_image image=&#8221;7487&#8243; img_size=&#8221;full&#8221; add_caption=&#8221;yes&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text el_class=&#8221;m-blog-text-right&#8221;]<\/p>\n<p>Die Hurricane Factory erf\u00fcllt den Traum vom Fliegen<\/p>\n<p>Fliegen ist seit jeher ein Menschheitstraum. Da wir aber leider anatomisch nicht f\u00fcr die bodenferne Fortbewegung geeignet sind, suchen wir immer wieder nach neuen M\u00f6glichkeiten, uns so schwerelos wie m\u00f6glich zu f\u00fchlen. Schwerelosigkeit gibt es seit Neuestem auch in Sch\u00f6nefeld: Hier hat vor kurzem erst der bislang gr\u00f6\u00dfte Windkanal Deutschlands [&#8230;]<\/p>\n<img src=\"https:\/\/mr-congress.com\/de\/wp-content\/uploads\/sites\/3\/2017\/08\/Hurricane_Factory_Windkanal_Flieger.jpg\" class=\"ss-hidden-pin-image\" alt=\"hurricane factory berlin, hurricane factory, hurricane factory prague, hurricane factory madrid, fliegen, windkanal, windkanal berlin, hurricane, flugsimulator, sch\u00f6nefeld, BER, berlin sch\u00f6nefeld, fliegen, location berlin, sightseeing berlin, must see berlin, adventure berlin, abenteuer berlin, action, action berlin, flight simulator berlin, adrenalin berlin,\" data-pin-url=\"https:\/\/mr-congress.com\/de\/2017\/09\/08\/hurricane_factory_berlin\/\" data-pin-media=\"https:\/\/mr-congress.com\/de\/wp-content\/uploads\/sites\/3\/2017\/08\/Hurricane_Factory_Windkanal_Flieger.jpg\" data-pin-description=\"Hurricane Factory Berlin\"\/>","protected":false},"author":5,"featured_media":7485,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":[],"categories":[690],"tags":[394,395,396,398,393,379,118,391,9,392,92,93,114,113,385,397,389,380,388,382,381,384,383,218,207,235,155,234,333,95,374,115,390,373,369,371,372,386,387],"_links":{"self":[{"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/posts\/7477"}],"collection":[{"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/comments?post=7477"}],"version-history":[{"count":3,"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/posts\/7477\/revisions"}],"predecessor-version":[{"id":24426,"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/posts\/7477\/revisions\/24426"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/media\/7485"}],"wp:attachment":[{"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/media?parent=7477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/categories?post=7477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mr-congress.com\/de\/wp-json\/wp\/v2\/tags?post=7477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}